{"id":1789,"date":"2016-11-21T18:30:08","date_gmt":"2016-11-21T17:30:08","guid":{"rendered":"http:\/\/service.ptmsrl.com\/de\/?page_id=1789"},"modified":"2016-11-21T18:30:34","modified_gmt":"2016-11-21T17:30:34","slug":"eine-automatische-ladung-starten-wenn-die-ladung-von-rezepten-beim-wiegecomputer-aktiv-ist","status":"publish","type":"page","link":"https:\/\/service.ptmsrl.com\/de\/arbeitsweise-vom-wiegecomputer\/eine-automatische-ladung-starten-wenn-die-ladung-von-rezepten-beim-wiegecomputer-aktiv-ist\/","title":{"rendered":"Eine automatische Ladung starten (wenn die Ladung von Rezepten beim Wiegecomputer aktiv ist)"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8220;section&#8220; fullwidth=&#8220;on&#8220;][et_pb_fullwidth_header admin_label=&#8220;Header &#8211; Centralina GSA&#8220; title=&#8220;GSA&#8220; background_layout=&#8220;dark&#8220; text_orientation=&#8220;left&#8220; header_fullscreen=&#8220;off&#8220; header_scroll_down=&#8220;off&#8220; background_color=&#8220;#222349&#8243; parallax=&#8220;off&#8220; parallax_method=&#8220;off&#8220; content_orientation=&#8220;center&#8220; image_orientation=&#8220;center&#8220; title_font_color=&#8220;#ffffff&#8220; title_font=&#8220;Montserrat|on|||&#8220; title_font_size=&#8220;40px&#8220; custom_button_one=&#8220;off&#8220; button_one_letter_spacing=&#8220;0&#8243; button_one_use_icon=&#8220;default&#8220; button_one_icon_placement=&#8220;right&#8220; button_one_on_hover=&#8220;on&#8220; button_one_letter_spacing_hover=&#8220;0&#8243; custom_button_two=&#8220;off&#8220; button_two_letter_spacing=&#8220;0&#8243; button_two_use_icon=&#8220;default&#8220; button_two_icon_placement=&#8220;right&#8220; button_two_on_hover=&#8220;on&#8220; button_two_letter_spacing_hover=&#8220;0&#8243;] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=&#8220;Sezione&#8220; fullwidth=&#8220;off&#8220; specialty=&#8220;on&#8220; transparent_background=&#8220;off&#8220; background_color=&#8220;#ffffff&#8220; allow_player_pause=&#8220;off&#8220; inner_shadow=&#8220;off&#8220; parallax=&#8220;off&#8220; parallax_method=&#8220;off&#8220; custom_padding=&#8220;0px|||&#8220; padding_mobile=&#8220;off&#8220; make_fullwidth=&#8220;off&#8220; use_custom_width=&#8220;off&#8220; width_unit=&#8220;on&#8220; make_equal=&#8220;off&#8220; use_custom_gutter=&#8220;off&#8220; parallax_1=&#8220;off&#8220; parallax_method_1=&#8220;off&#8220; parallax_2=&#8220;off&#8220; parallax_method_2=&#8220;off&#8220; custom_css_main_1=&#8220;border-right: solid 1px #bababa;&#8220;][et_pb_column type=&#8220;1_4&#8243;][et_pb_blurb admin_label=&#8220;Link al prodotto &#8211; CENTRALINA GSA&#8220; global_module=&#8220;1498&#8243; saved_tabs=&#8220;all&#8220; title=&#8220;Scheda prodotto&#8220; url=&#8220;http:\/\/www.ptmsrl.com\/it\/s10\/product\/&#8220; url_new_window=&#8220;on&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%101%%&#8220; icon_color=&#8220;#b5b5b5&#8243; use_circle=&#8220;off&#8220; circle_color=&#8220;#0d76ec&#8220; use_circle_border=&#8220;off&#8220; circle_border_color=&#8220;#0d76ec&#8220; icon_placement=&#8220;left&#8220; animation=&#8220;top&#8220; background_layout=&#8220;light&#8220; text_orientation=&#8220;left&#8220; use_icon_font_size=&#8220;off&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220;] Centralina GSA [\/et_pb_blurb][et_pb_divider admin_label=&#8220;Modulo Separatore&#8220; color=&#8220;#b5b5b5&#8243; show_divider=&#8220;on&#8220; divider_style=&#8220;solid&#8220; divider_position=&#8220;top&#8220; hide_on_mobile=&#8220;on&#8220; height=&#8220;10&#8243;] [\/et_pb_divider][et_pb_text admin_label=&#8220;MENU LATERALE &#8211; CENTRALINA GSA&#8220; background_layout=&#8220;light&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; saved_tabs=&#8220;all&#8220; global_module=&#8220;1502&#8243;]<\/p>\n<p><strong>APP MYSCALE<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/\">Introduzione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-installazione-dellapp\/\">Installazione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-attivazione-della-modalita-myscale\/\">Attivazione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-segnalazioni-di-stato\/\">Segnalazioni di stato<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-stato-della-connessione\/\">Stato della connessione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-funzione-dei-tasti\/\">Funzione dei tasti<\/a><\/li>\n<li>Utilizzo del sistema\n<ul>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-utilizzo-della-tastiera\/\">Tastiera<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale\/\">Peso totale<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-selezione-della-ricetta\/\">Selezione della ricetta<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-azzeramento-del-peso-totale\/\">Azzeramento del peso totale<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-carico-avvio-del-carico-della-ricetta\/\">Peso totale carico<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-scarico-avvio-dello-scarico-della-ricetta\/\">Peso totale scarico<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-parziale-azzeramento-del-peso-parziale\/\">Peso parziale<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;3_4&#8243; specialty_columns=&#8220;3&#8243;][et_pb_row_inner admin_label=&#8220;Riga&#8220;][et_pb_column_inner type=&#8220;4_4&#8243; saved_specialty_column_type=&#8220;3_4&#8243;][et_pb_cta admin_label=&#8220;Titolo sezione&#8220; title=&#8220;Eine automatische Ladung starten (wenn die Ladung von Rezepten beim Wiegecomputer aktiv ist)&#8220; url_new_window=&#8220;off&#8220; use_background_color=&#8220;off&#8220; background_color=&#8220;#0d76ec&#8220; background_layout=&#8220;light&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; custom_button=&#8220;off&#8220; button_letter_spacing=&#8220;0&#8243; button_use_icon=&#8220;default&#8220; button_icon_placement=&#8220;right&#8220; button_on_hover=&#8220;on&#8220; button_letter_spacing_hover=&#8220;0&#8243; header_font_size=&#8220;40&#8243;] [\/et_pb_cta][et_pb_text admin_label=&#8220;Testo&#8220; background_layout=&#8220;light&#8220; text_orientation=&#8220;left&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220;]<\/p>\n<p>Um die automatische Ladung eines Rezeptes zu starten, die folgenden Operationen ausf\u00fchren:<\/p>\n<ul>\n<li>Ins Men\u00fc &#8222;Gesamtgewicht&#8220; eintreten und die Taste \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1544\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0011_gsa.jpg\" alt=\"centralina__0011_gsa\" width=\"54\" height=\"40\" \/> bet\u00e4tigen.<\/li>\n<li>Das gew\u00fcnschte Rezept durch die Tasten \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1552\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0019_gsa.jpg\" alt=\"centralina__0019_gsa\" width=\"54\" height=\"40\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1551\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0018_gsa.jpg\" alt=\"centralina__0018_gsa\" width=\"54\" height=\"40\" \/> ausw\u00e4hlen, und die Auswahl mit der Taste \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1555\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0022_gsa.jpg\" alt=\"centralina__0022_gsa\" width=\"54\" height=\"40\" \/>\u00a0 best\u00e4tigen<\/li>\n<li>Wenn n\u00f6tig, auch die zu ladende Menge durch die Taste \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1555\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0022_gsa.jpg\" alt=\"centralina__0022_gsa\" width=\"54\" height=\"40\" \/> \u00e4ndern. In die Funktion &#8222;\u00c4nderung&#8220; eintreten und durch die alphanumerische Tastatur die zu ladende Menge eingeben. Die Taste \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1542\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0009_gsa.jpg\" alt=\"centralina__0009_gsa\" width=\"54\" height=\"40\" \/> dr\u00fccken, um den eingestellten Wert zu best\u00e4tigen.<\/li>\n<li>Durch die Taste <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1555\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0022_gsa.jpg\" alt=\"centralina__0022_gsa\" width=\"54\" height=\"40\" \/>\u00a0den Rezeptstart best\u00e4tigen.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Achtung: die Ladung des Rezepts kann in folgenden F\u00e4llen nicht starten:<\/p>\n<ul>\n<li>ein Nullstellungsfehler tritt beim Ladungsstart auf, weil das Material in der Wanne h\u00f6her als die maximale Nullstellungsgrenze ist.<\/li>\n<li>die Restmenge in der Wanne ist h\u00f6her als die maximale in den Coden eingestellte Restgrenze.<\/li>\n<li>die Summe der zu ladenden Menge und der Restmenge in der Wanne (beim Ladungsstart) ist h\u00f6her als die Grenze von &#8220; FEHLER BEHAELTER !!!&#8220;.<\/li>\n<li>die zu ladenden Rezeptmenge ist h\u00f6her als der Wert von &#8220; FEHLER BEHAELTER !!!&#8220;.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1733 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0017_gsa-de.jpg\" width=\"134\" height=\"101\" \/>\u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1732 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0016_gsa-de.jpg\" width=\"134\" height=\"101\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1731 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0015_gsa-de.jpg\" width=\"134\" height=\"101\" \/>\u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1730 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0014_gsa-de.jpg\" width=\"134\" height=\"101\" \/><\/p>\n<p>[\/et_pb_text][et_pb_divider admin_label=&#8220;Modulo Separatore&#8220; color=&#8220;#bababa&#8220; show_divider=&#8220;on&#8220; height=&#8220;10&#8243; divider_style=&#8220;solid&#8220; divider_position=&#8220;top&#8220; hide_on_mobile=&#8220;on&#8220;] [\/et_pb_divider][et_pb_cta admin_label=&#8220;Link al form&#8220; global_module=&#8220;142&#8243; saved_tabs=&#8220;all&#8220; title=&#8220;Non trovi quello che cerchi?&#8220; button_url=&#8220;#&#8220; url_new_window=&#8220;off&#8220; button_text=&#8220;Contattaci&#8220; use_background_color=&#8220;off&#8220; background_color=&#8220;#0d76ec&#8220; background_layout=&#8220;light&#8220; text_orientation=&#8220;center&#8220; use_border_color=&#8220;off&#8220; border_color=&#8220;#ffffff&#8220; border_style=&#8220;solid&#8220; custom_button=&#8220;off&#8220; button_letter_spacing=&#8220;0&#8243; button_use_icon=&#8220;default&#8220; button_icon_placement=&#8220;right&#8220; button_on_hover=&#8220;on&#8220; button_letter_spacing_hover=&#8220;0&#8243;] [\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centralina GSA APP MYSCALE Introduzione Installazione Attivazione Segnalazioni di stato Stato della connessione Funzione dei tasti Utilizzo del sistema Tastiera Peso totale Selezione della ricetta Azzeramento del peso totale Peso totale carico Peso totale scarico Peso parziale Um die automatische Ladung eines Rezeptes zu starten, die folgenden Operationen ausf\u00fchren: Ins Men\u00fc &#8222;Gesamtgewicht&#8220; eintreten und die [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":1749,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>[et_pb_section admin_label=\"section\" global_module=\"1495\" fullwidth=\"on\"][et_pb_fullwidth_header global_parent=\"1495\" admin_label=\"Header - Centralina GSA\" title=\"CENTRALINA GSA\" background_layout=\"dark\" text_orientation=\"left\" header_fullscreen=\"off\" header_scroll_down=\"off\" background_color=\"#222349\" parallax=\"off\" parallax_method=\"off\" content_orientation=\"center\" image_orientation=\"center\" title_font_color=\"#ffffff\" title_font=\"Montserrat|on|||\" title_font_size=\"40px\" custom_button_one=\"off\" button_one_letter_spacing=\"0\" button_one_use_icon=\"default\" button_one_icon_placement=\"right\" button_one_on_hover=\"on\" button_one_letter_spacing_hover=\"0\" custom_button_two=\"off\" button_two_letter_spacing=\"0\" button_two_use_icon=\"default\" button_two_icon_placement=\"right\" button_two_on_hover=\"on\" button_two_letter_spacing_hover=\"0\"] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=\"Sezione\" fullwidth=\"off\" specialty=\"on\" transparent_background=\"off\" background_color=\"#ffffff\" allow_player_pause=\"off\" inner_shadow=\"off\" parallax=\"off\" parallax_method=\"off\" custom_padding=\"0px|||\" padding_mobile=\"off\" make_fullwidth=\"off\" use_custom_width=\"off\" width_unit=\"on\" make_equal=\"off\" use_custom_gutter=\"off\" parallax_1=\"off\" parallax_method_1=\"off\" parallax_2=\"off\" parallax_method_2=\"off\" custom_css_main_1=\"border-right: solid 1px #bababa;\"][et_pb_column type=\"1_4\"][et_pb_blurb admin_label=\"Link al prodotto - CENTRALINA GSA\" global_module=\"1498\" saved_tabs=\"all\" title=\"Scheda prodotto\" url=\"http:\/\/www.ptmsrl.com\/it\/s10\/product\/\" url_new_window=\"on\" use_icon=\"on\" font_icon=\"%%101%%\" icon_color=\"#b5b5b5\" use_circle=\"off\" circle_color=\"#0d76ec\" use_circle_border=\"off\" circle_border_color=\"#0d76ec\" icon_placement=\"left\" animation=\"top\" background_layout=\"light\" text_orientation=\"left\" use_icon_font_size=\"off\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"] Centralina GSA [\/et_pb_blurb][et_pb_divider admin_label=\"Modulo Separatore\" color=\"#b5b5b5\" show_divider=\"on\" divider_style=\"solid\" divider_position=\"top\" hide_on_mobile=\"on\" height=\"10\"] [\/et_pb_divider][et_pb_text admin_label=\"MENU LATERALE - CENTRALINA GSA\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" saved_tabs=\"all\" global_module=\"1502\"]<\/p><p><strong>APP MYSCALE<\/strong><\/p><ul><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/\">Introduzione<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-installazione-dellapp\/\">Installazione<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-attivazione-della-modalita-myscale\/\">Attivazione<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-segnalazioni-di-stato\/\">Segnalazioni di stato<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-stato-della-connessione\/\">Stato della connessione<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-funzione-dei-tasti\/\">Funzione dei tasti<\/a><\/li><li>Utilizzo del sistema<ul><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-utilizzo-della-tastiera\/\">Tastiera<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale\/\">Peso totale<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-selezione-della-ricetta\/\">Selezione della ricetta<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-azzeramento-del-peso-totale\/\">Azzeramento del peso totale<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-carico-avvio-del-carico-della-ricetta\/\">Peso totale carico<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-scarico-avvio-dello-scarico-della-ricetta\/\">Peso totale scarico<\/a><\/li><li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-parziale-azzeramento-del-peso-parziale\/\">Peso parziale<\/a><\/li><\/ul><\/li><\/ul><p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\"3_4\" specialty_columns=\"3\"][et_pb_row_inner admin_label=\"Riga\"][et_pb_column_inner type=\"4_4\" saved_specialty_column_type=\"3_4\"][et_pb_cta admin_label=\"Titolo sezione\" title=\"Avvio di un carico automatico (se la centralina \u00e8 abilitata al carico delle ricette)\" url_new_window=\"off\" use_background_color=\"off\" background_color=\"#0d76ec\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" custom_button=\"off\" button_letter_spacing=\"0\" button_use_icon=\"default\" button_icon_placement=\"right\" button_on_hover=\"on\" button_letter_spacing_hover=\"0\" header_font_size=\"40\"] [\/et_pb_cta][et_pb_text admin_label=\"Testo\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"]<\/p><p>Per avviare il carico automatico di una ricetta \u00e8 necessario effettuare le seguenti operazioni:<\/p><ul><li>Posizionarsi all\u2019interno del menu di peso totale e premere\u00a0<img class=\"alignnone size-full wp-image-1544\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0011_gsa.jpg\" alt=\"centralina__0011_gsa\" width=\"54\" height=\"40\" \/><\/li><li>Selezionare la ricetta da caricare utilizzando i tasti \u00a0<img class=\"alignnone size-full wp-image-1552\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0019_gsa.jpg\" alt=\"centralina__0019_gsa\" width=\"54\" height=\"40\" \/>e \u00a0 \u00a0\u00a0<img class=\"alignnone size-full wp-image-1551\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0018_gsa.jpg\" alt=\"centralina__0018_gsa\" width=\"54\" height=\"40\" \/>, confermando la scelta mediante la pressione del tasto\u00a0<img class=\"alignnone size-full wp-image-1555\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0022_gsa.jpg\" alt=\"centralina__0022_gsa\" width=\"54\" height=\"40\" \/><\/li><li>Eventualmente modificare la quantit\u00e0 da caricare premendo il tasto <img class=\"alignnone size-full wp-image-1542\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0009_gsa.jpg\" alt=\"centralina__0009_gsa\" width=\"54\" height=\"40\" \/>. Una volta in \u201cmodalit\u00e0 modifica\u201d digitare con il tastierino numerico la quantit\u00e0 da caricare e premere <img class=\"alignnone size-full wp-image-1555\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0022_gsa.jpg\" alt=\"centralina__0022_gsa\" width=\"54\" height=\"40\" \/>\u00a0per confermare.<\/li><li>Confermare l\u2019avvio della ricetta premendo il tasto\u00a0<img class=\"alignnone size-full wp-image-1555\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0022_gsa.jpg\" alt=\"centralina__0022_gsa\" width=\"54\" height=\"40\" \/>.<\/li><\/ul><p>Si ricorda all\u2019utente che il carico della ricetta NON partir\u00e0 nel caso si rientri in una delle seguenti condizioni:<\/p><ul><li>Si verifica un errore di azzeramento all\u2019avvio del carico in quanto il materiale presente in vasca \u00e8 superiore alla soglia di azzeramento massima.<\/li><li>La rimanenza presente in vasca \u00e8 oltre la soglia di rimanenza massima impostata nei codici.<\/li><li>La quantit\u00e0 da caricare sommata al valore della rimanenza presente in vasca all\u2019avvio del carico d\u00e0 un risultato che supera la soglia di \u201cErrore Vasca\u201d.<\/li><\/ul><p>La quantit\u00e0 da caricare della ricetta \u00e8 oltre il valore di \u201cErrore Vasca\u201d.<\/p><p>\u00a0<\/p><p><img class=\"alignnone size-full wp-image-1582\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0017_centralina-gsa.jpg\" alt=\"ptm__0017_centralina-gsa\" width=\"224\" height=\"168\" \/>\u00a0 \u00a0<img class=\"alignnone size-full wp-image-1581\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0016_centralina-gsa.jpg\" alt=\"ptm__0016_centralina-gsa\" width=\"224\" height=\"168\" \/><\/p><p><img class=\"alignnone size-full wp-image-1580\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0015_centralina-gsa.jpg\" alt=\"ptm__0015_centralina-gsa\" width=\"224\" height=\"168\" \/>\u00a0 \u00a0<img class=\"alignnone size-full wp-image-1579\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0014_centralina-gsa.jpg\" alt=\"ptm__0014_centralina-gsa\" width=\"224\" height=\"168\" \/><\/p><p>[\/et_pb_text][et_pb_divider admin_label=\"Modulo Separatore\" color=\"#bababa\" show_divider=\"on\" height=\"10\" divider_style=\"solid\" divider_position=\"top\" hide_on_mobile=\"on\"] [\/et_pb_divider][et_pb_cta admin_label=\"Link al form\" global_module=\"142\" saved_tabs=\"all\" title=\"Non trovi quello che cerchi?\" button_url=\"#\" url_new_window=\"off\" button_text=\"Contattaci\" use_background_color=\"off\" background_color=\"#0d76ec\" background_layout=\"light\" text_orientation=\"center\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" custom_button=\"off\" button_letter_spacing=\"0\" button_use_icon=\"default\" button_icon_placement=\"right\" button_on_hover=\"on\" button_letter_spacing_hover=\"0\"] [\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/service.ptmsrl.com\/de\/wp-json\/wp\/v2\/pages\/1789"}],"collection":[{"href":"https:\/\/service.ptmsrl.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/service.ptmsrl.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/service.ptmsrl.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/service.ptmsrl.com\/de\/wp-json\/wp\/v2\/comments?post=1789"}],"version-history":[{"count":0,"href":"https:\/\/service.ptmsrl.com\/de\/wp-json\/wp\/v2\/pages\/1789\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/service.ptmsrl.com\/de\/wp-json\/wp\/v2\/pages\/1749"}],"wp:attachment":[{"href":"https:\/\/service.ptmsrl.com\/de\/wp-json\/wp\/v2\/media?parent=1789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}