{"id":2009,"date":"2016-11-21T10:28:14","date_gmt":"2016-11-21T09:28:14","guid":{"rendered":"http:\/\/service.ptmsrl.com\/es\/gsa\/centralina-gsa-carico-parziale-con-azzeramento-del-peso\/"},"modified":"2016-11-29T16:54:24","modified_gmt":"2016-11-29T15:54:24","slug":"carga-parcial-con-ajuste-de-cero-del-peso","status":"publish","type":"page","link":"http:\/\/service.ptmsrl.com\/es\/gsa\/carga-parcial-con-ajuste-de-cero-del-peso\/","title":{"rendered":"Carga parcial con ajuste de cero del peso"},"content":{"rendered":"<p>[et_pb_section admin_label=\u00bbsection\u00bb fullwidth=\u00bbon\u00bb][et_pb_fullwidth_header admin_label=\u00bbHeader &#8211; Centralina GSA\u00bb title=\u00bbGSA\u00bb background_layout=\u00bbdark\u00bb text_orientation=\u00bbleft\u00bb header_fullscreen=\u00bboff\u00bb header_scroll_down=\u00bboff\u00bb background_color=\u00bb#222349&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bboff\u00bb content_orientation=\u00bbcenter\u00bb image_orientation=\u00bbcenter\u00bb title_font_color=\u00bb#ffffff\u00bb title_font=\u00bbMontserrat|on|||\u00bb title_font_size=\u00bb40px\u00bb custom_button_one=\u00bboff\u00bb button_one_letter_spacing=\u00bb0&#8243; button_one_use_icon=\u00bbdefault\u00bb button_one_icon_placement=\u00bbright\u00bb button_one_on_hover=\u00bbon\u00bb button_one_letter_spacing_hover=\u00bb0&#8243; custom_button_two=\u00bboff\u00bb button_two_letter_spacing=\u00bb0&#8243; button_two_use_icon=\u00bbdefault\u00bb button_two_icon_placement=\u00bbright\u00bb button_two_on_hover=\u00bbon\u00bb button_two_letter_spacing_hover=\u00bb0&#8243;] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=\u00bbSezione\u00bb fullwidth=\u00bboff\u00bb specialty=\u00bbon\u00bb transparent_background=\u00bboff\u00bb background_color=\u00bb#ffffff\u00bb allow_player_pause=\u00bboff\u00bb inner_shadow=\u00bboff\u00bb parallax=\u00bboff\u00bb parallax_method=\u00bboff\u00bb custom_padding=\u00bb0px|||\u00bb padding_mobile=\u00bboff\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb make_equal=\u00bboff\u00bb use_custom_gutter=\u00bboff\u00bb parallax_1=\u00bboff\u00bb parallax_method_1=\u00bboff\u00bb parallax_2=\u00bboff\u00bb parallax_method_2=\u00bboff\u00bb custom_css_main_1=\u00bbborder-right: solid 1px #bababa;\u00bb][et_pb_column type=\u00bb1_4&#8243;][et_pb_blurb admin_label=\u00bbLink al prodotto &#8211; CENTRALINA GSA\u00bb global_module=\u00bb1498&#8243; saved_tabs=\u00bball\u00bb title=\u00bbScheda prodotto\u00bb url=\u00bbhttp:\/\/www.ptmsrl.com\/it\/s10\/product\/\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb%%101%%\u00bb icon_color=\u00bb#b5b5b5&#8243; use_circle=\u00bboff\u00bb circle_color=\u00bb#0d76ec\u00bb use_circle_border=\u00bboff\u00bb circle_border_color=\u00bb#0d76ec\u00bb icon_placement=\u00bbleft\u00bb animation=\u00bbtop\u00bb background_layout=\u00bblight\u00bb text_orientation=\u00bbleft\u00bb use_icon_font_size=\u00bboff\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb] Centralina GSA [\/et_pb_blurb][et_pb_divider admin_label=\u00bbModulo Separatore\u00bb color=\u00bb#b5b5b5&#8243; show_divider=\u00bbon\u00bb divider_style=\u00bbsolid\u00bb divider_position=\u00bbtop\u00bb hide_on_mobile=\u00bbon\u00bb height=\u00bb10&#8243;] [\/et_pb_divider][et_pb_text admin_label=\u00bbMENU LATERALE &#8211; CENTRALINA GSA\u00bb background_layout=\u00bblight\u00bb text_orientation=\u00bbleft\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb saved_tabs=\u00bball\u00bb global_module=\u00bb1502&#8243;]<\/p>\n<p><strong>APP MYSCALE<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/\">Introduzione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-installazione-dellapp\/\">Installazione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-attivazione-della-modalita-myscale\/\">Attivazione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-segnalazioni-di-stato\/\">Segnalazioni di stato<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-stato-della-connessione\/\">Stato della connessione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-funzione-dei-tasti\/\">Funzione dei tasti<\/a><\/li>\n<li>Utilizzo del sistema\n<ul>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-utilizzo-della-tastiera\/\">Tastiera<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale\/\">Peso totale<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-selezione-della-ricetta\/\">Selezione della ricetta<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-azzeramento-del-peso-totale\/\">Azzeramento del peso totale<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-carico-avvio-del-carico-della-ricetta\/\">Peso totale carico<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-scarico-avvio-dello-scarico-della-ricetta\/\">Peso totale scarico<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-parziale-azzeramento-del-peso-parziale\/\">Peso parziale<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; specialty_columns=\u00bb3&#8243;][et_pb_row_inner admin_label=\u00bbRiga\u00bb][et_pb_column_inner type=\u00bb4_4&#8243; saved_specialty_column_type=\u00bb3_4&#8243;][et_pb_cta admin_label=\u00bbTitolo sezione\u00bb title=\u00bbCarga parcial con ajuste de cero del peso\u00bb url_new_window=\u00bboff\u00bb use_background_color=\u00bboff\u00bb background_color=\u00bb#0d76ec\u00bb background_layout=\u00bblight\u00bb text_orientation=\u00bbleft\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb custom_button=\u00bboff\u00bb button_letter_spacing=\u00bb0&#8243; button_use_icon=\u00bbdefault\u00bb button_icon_placement=\u00bbright\u00bb button_on_hover=\u00bbon\u00bb button_letter_spacing_hover=\u00bb0&#8243; header_font_size=\u00bb40&#8243;] [\/et_pb_cta][et_pb_text admin_label=\u00bbTesto\u00bb background_layout=\u00bblight\u00bb text_orientation=\u00bbleft\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p>Apretar la tecla \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1547\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0014_gsa.jpg\" alt=\"centralina__0014_gsa\" width=\"54\" height=\"40\" \/>para poner a cero el peso parcial; depu\u00e9s la presi\u00f3n de la tecla la pantalla muestra el peso parcial cargado (desde ese momento) y en la parte abajo de la pantalla se lee el peso total.<\/p>\n<p>Para poner a cero el peso parcial cargado, apretar de nuevo la tecla <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1547\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0014_gsa.jpg\" alt=\"centralina__0014_gsa\" width=\"54\" height=\"40\" \/><\/p>\n<p>Pulsar \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1548\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/centralina__0015_gsa.jpg\" alt=\"centralina__0015_gsa\" width=\"54\" height=\"40\" \/>para regresar en el men\u00fa de peso total.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1962 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0022_gsa-esp.jpg\" width=\"134\" height=\"101\" \/>\u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1961 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0021_gsa-esp.jpg\" width=\"134\" height=\"101\" \/>\u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1960 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm__0020_gsa-esp.jpg\" width=\"134\" height=\"101\" \/><\/p>\n<p>[\/et_pb_text][et_pb_divider admin_label=\u00bbModulo Separatore\u00bb color=\u00bb#bababa\u00bb show_divider=\u00bbon\u00bb height=\u00bb10&#8243; divider_style=\u00bbsolid\u00bb divider_position=\u00bbtop\u00bb hide_on_mobile=\u00bbon\u00bb] [\/et_pb_divider][et_pb_cta admin_label=\u00bbLink al form\u00bb global_module=\u00bb142&#8243; saved_tabs=\u00bball\u00bb title=\u00bbNon trovi quello che cerchi?\u00bb button_url=\u00bb#\u00bb url_new_window=\u00bboff\u00bb button_text=\u00bbContattaci\u00bb use_background_color=\u00bboff\u00bb background_color=\u00bb#0d76ec\u00bb background_layout=\u00bblight\u00bb text_orientation=\u00bbcenter\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb custom_button=\u00bboff\u00bb button_letter_spacing=\u00bb0&#8243; button_use_icon=\u00bbdefault\u00bb button_icon_placement=\u00bbright\u00bb button_on_hover=\u00bbon\u00bb button_letter_spacing_hover=\u00bb0&#8243;] [\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centralina GSA APP MYSCALE Introduzione Installazione Attivazione Segnalazioni di stato Stato della connessione Funzione dei tasti Utilizzo del sistema Tastiera Peso totale Selezione della ricetta Azzeramento del peso totale Peso totale carico Peso totale scarico Peso parziale Apretar la tecla \u00a0\u00a0para poner a cero el peso parcial; depu\u00e9s la presi\u00f3n de la tecla la pantalla [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":1930,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"http:\/\/service.ptmsrl.com\/es\/wp-json\/wp\/v2\/pages\/2009"}],"collection":[{"href":"http:\/\/service.ptmsrl.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/service.ptmsrl.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/es\/wp-json\/wp\/v2\/comments?post=2009"}],"version-history":[{"count":0,"href":"http:\/\/service.ptmsrl.com\/es\/wp-json\/wp\/v2\/pages\/2009\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/es\/wp-json\/wp\/v2\/pages\/1930"}],"wp:attachment":[{"href":"http:\/\/service.ptmsrl.com\/es\/wp-json\/wp\/v2\/media?parent=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}