{"id":837,"date":"2016-11-08T11:41:06","date_gmt":"2016-11-08T10:41:06","guid":{"rendered":"http:\/\/demo.n-3.it\/ptm\/en\/?page_id=837"},"modified":"2016-11-08T15:41:47","modified_gmt":"2016-11-08T14:41:47","slug":"personal-customers-data","status":"publish","type":"page","link":"http:\/\/service.ptmsrl.com\/en\/super-datamix\/personal-customers-data\/","title":{"rendered":"Personal customers data"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8221;section&#8221; fullwidth=&#8221;on&#8221;][et_pb_fullwidth_header admin_label=&#8221;Intestazione a Larghezza Piena&#8221; title=&#8221;SUPER DATAMIX 5&#8243; background_layout=&#8221;dark&#8221; text_orientation=&#8221;left&#8221; header_fullscreen=&#8221;off&#8221; header_scroll_down=&#8221;off&#8221; background_color=&#8221;#222349&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; content_orientation=&#8221;center&#8221; image_orientation=&#8221;center&#8221; title_font=&#8221;Montserrat|on|||&#8221; title_font_size=&#8221;40px&#8221; custom_button_one=&#8221;off&#8221; button_one_letter_spacing=&#8221;0&#8243; button_one_use_icon=&#8221;default&#8221; button_one_icon_placement=&#8221;right&#8221; button_one_on_hover=&#8221;on&#8221; button_one_letter_spacing_hover=&#8221;0&#8243; custom_button_two=&#8221;off&#8221; button_two_letter_spacing=&#8221;0&#8243; button_two_use_icon=&#8221;default&#8221; button_two_icon_placement=&#8221;right&#8221; button_two_on_hover=&#8221;on&#8221; button_two_letter_spacing_hover=&#8221;0&#8243; title_font_color=&#8221;#ffffff&#8221;] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=&#8221;Sezione&#8221; fullwidth=&#8221;off&#8221; specialty=&#8221;on&#8221; transparent_background=&#8221;off&#8221; background_color=&#8221;#ffffff&#8221; allow_player_pause=&#8221;off&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;0px|||&#8221; padding_mobile=&#8221;off&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221; make_equal=&#8221;off&#8221; use_custom_gutter=&#8221;off&#8221; parallax_1=&#8221;off&#8221; parallax_method_1=&#8221;off&#8221; parallax_2=&#8221;off&#8221; parallax_method_2=&#8221;off&#8221; custom_css_main_1=&#8221;border-right: solid 1px #bababa;&#8221;][et_pb_column type=&#8221;1_4&#8243;][et_pb_blurb admin_label=&#8221;Link al prodotto &#8211; SUPER DATAMIX &#8211; ITA&#8221; global_module=&#8221;710&#8243; saved_tabs=&#8221;all&#8221; title=&#8221;Scheda prodotto&#8221; url=&#8221;http:\/\/www.ptmsrl.com\/it\/s34\/product\/&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%101%%&#8221; icon_color=&#8221;#b5b5b5&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#0d76ec&#8221; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#0d76ec&#8221; icon_placement=&#8221;left&#8221; animation=&#8221;top&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_icon_font_size=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<br \/>\n[\/et_pb_blurb][et_pb_divider admin_label=&#8221;Modulo Separatore&#8221; color=&#8221;#b5b5b5&#8243; show_divider=&#8221;on&#8221; divider_style=&#8221;solid&#8221; divider_position=&#8221;top&#8221; hide_on_mobile=&#8221;on&#8221; height=&#8221;10&#8243;]<br \/>\n[\/et_pb_divider][et_pb_text admin_label=&#8221;Menu laterale &#8211; SUPER DATAMIX &#8211; ITA&#8221; global_module=&#8221;714&#8243; saved_tabs=&#8221;all&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; text_font_size=&#8221;16&#8243; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p><strong>SUPER DATAMIX<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/\">Introduzione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-installazione-dellapp\/\">Installazione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-attivazione-della-modalita-myscale\/\">Attivazione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-segnalazioni-di-stato\/\">Segnalazioni di stato<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-stato-della-connessione\/\">Stato della connessione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-funzione-dei-tasti\/\">Funzione dei tasti<\/a><\/li>\n<li>Utilizzo del sistema\n<ul>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-utilizzo-della-tastiera\/\">Tastiera<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale\/\">Peso totale<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-selezione-della-ricetta\/\">Selezione della ricetta<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-azzeramento-del-peso-totale\/\">Azzeramento del peso totale<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-carico-avvio-del-carico-della-ricetta\/\">Peso totale carico<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-scarico-avvio-dello-scarico-della-ricetta\/\">Peso totale scarico<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-parziale-azzeramento-del-peso-parziale\/\">Peso parziale<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; specialty_columns=&#8221;3&#8243;][et_pb_row_inner admin_label=&#8221;Riga&#8221;][et_pb_column_inner type=&#8221;4_4&#8243; saved_specialty_column_type=&#8221;3_4&#8243;][et_pb_cta admin_label=&#8221;Titolo sezione&#8221; title=&#8221;Personal customers data&#8221; url_new_window=&#8221;off&#8221; use_background_color=&#8221;off&#8221; background_color=&#8221;#0d76ec&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; custom_button=&#8221;off&#8221; button_letter_spacing=&#8221;0&#8243; button_use_icon=&#8221;default&#8221; button_icon_placement=&#8221;right&#8221; button_on_hover=&#8221;on&#8221; button_letter_spacing_hover=&#8221;0&#8243; header_font_size=&#8221;40&#8243;] [\/et_pb_cta][et_pb_text admin_label=&#8221;Testo&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-799\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm_0013_customers.jpg\" alt=\"ptm_0013_customers\" width=\"459\" height=\"333\" srcset=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm_0013_customers.jpg 459w, http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm_0013_customers-300x218.jpg 300w\" sizes=\"(max-width: 459px) 100vw, 459px\" \/><\/p>\n<p>In this menu it is possible to create a personal customers&#8217; register to utilize when creating the wagons<strong>. <\/strong><\/p>\n<p>In the left table [8] it is visualized the list of the inserted customers, whereas in the right side it is shown the full detail related to selected customer.<\/p>\n<p>For each customer they are mentioned following data:<\/p>\n<p>&#8211; <strong>Company name<\/strong> [10]: Customer&#8217;s Company Name (max. 40 alphanumeric characters)<\/p>\n<p>&#8211; <strong>Address<\/strong> [11]: customer&#8217;s address<\/p>\n<p>&#8211; <strong>Zip Code<\/strong> [12]: Postal Code Number<\/p>\n<p>&#8211; <strong>Municipality<\/strong> [13]: name of Town where customer is operating<\/p>\n<p>&#8211; <strong>District<\/strong> [13]: name of County where customer is operating<\/p>\n<p>&#8211; <strong>Country <\/strong>[15]: Nation where customer is located<\/p>\n<p>&#8211; <strong>Telephon<\/strong>e [16]: customer&#8217;s phone number<\/p>\n<p>&#8211; <strong>Fax <\/strong>[17]: customer&#8217;s fax number<\/p>\n<p>&#8211; <strong>E-mail<\/strong> [18]: customer&#8217;s e-mail address<\/p>\n<p>&#8211; <strong>VAT<\/strong> [19]: customer&#8217;s VAT<\/p>\n<p>&#8211; <strong>Notes<\/strong> [20]: remarks and notes regarding the customer<\/p>\n<p>&nbsp;<\/p>\n<p>If you wish to visualize a report concerning the inserted customers press &#8220;Print&#8221; [6].<\/p>\n<p>[\/et_pb_text][et_pb_divider admin_label=&#8221;Modulo Separatore&#8221; color=&#8221;#bababa&#8221; show_divider=&#8221;on&#8221; height=&#8221;10&#8243; divider_style=&#8221;solid&#8221; divider_position=&#8221;top&#8221; hide_on_mobile=&#8221;on&#8221;]<br \/>\n[\/et_pb_divider][et_pb_cta admin_label=&#8221;Link al form&#8221; global_module=&#8221;142&#8243; saved_tabs=&#8221;all&#8221; title=&#8221;Non trovi quello che cerchi?&#8221; button_url=&#8221;#&#8221; url_new_window=&#8221;off&#8221; button_text=&#8221;Contattaci&#8221; use_background_color=&#8221;off&#8221; background_color=&#8221;#0d76ec&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;center&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; custom_button=&#8221;off&#8221; button_letter_spacing=&#8221;0&#8243; button_use_icon=&#8221;default&#8221; button_icon_placement=&#8221;right&#8221; button_on_hover=&#8221;on&#8221; button_letter_spacing_hover=&#8221;0&#8243;]<br \/>\n[\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SUPER DATAMIX Introduzione Installazione Attivazione Segnalazioni di stato Stato della connessione Funzione dei tasti Utilizzo del sistema Tastiera Peso totale Selezione della ricetta Azzeramento del peso totale Peso totale carico Peso totale scarico Peso parziale In this menu it is possible to create a personal customers&#8217; register to utilize when creating the wagons. In the [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":785,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>[et_pb_section admin_label=\"section\" global_module=\"706\" fullwidth=\"on\"][et_pb_fullwidth_header global_parent=\"706\" admin_label=\"Intestazione a Larghezza Piena\" title=\"SUPER DATAMIX\" background_layout=\"dark\" text_orientation=\"left\" header_fullscreen=\"off\" header_scroll_down=\"off\" background_color=\"#222349\" parallax=\"off\" parallax_method=\"off\" content_orientation=\"center\" image_orientation=\"center\" title_font=\"Montserrat|on|||\" title_font_size=\"40px\" custom_button_one=\"off\" button_one_letter_spacing=\"0\" button_one_use_icon=\"default\" button_one_icon_placement=\"right\" button_one_on_hover=\"on\" button_one_letter_spacing_hover=\"0\" custom_button_two=\"off\" button_two_letter_spacing=\"0\" button_two_use_icon=\"default\" button_two_icon_placement=\"right\" button_two_on_hover=\"on\" button_two_letter_spacing_hover=\"0\" title_font_color=\"#ffffff\"] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=\"Sezione\" fullwidth=\"off\" specialty=\"on\" transparent_background=\"off\" background_color=\"#ffffff\" allow_player_pause=\"off\" inner_shadow=\"off\" parallax=\"off\" parallax_method=\"off\" custom_padding=\"0px|||\" padding_mobile=\"off\" make_fullwidth=\"off\" use_custom_width=\"off\" width_unit=\"on\" make_equal=\"off\" use_custom_gutter=\"off\" parallax_1=\"off\" parallax_method_1=\"off\" parallax_2=\"off\" parallax_method_2=\"off\" custom_css_main_1=\"border-right: solid 1px #bababa;\"][et_pb_column type=\"1_4\"][et_pb_blurb admin_label=\"Link al prodotto - SUPER DATAMIX - ITA\" global_module=\"710\" saved_tabs=\"all\" title=\"Scheda prodotto\" url=\"http:\/\/www.ptmsrl.com\/it\/s34\/product\/\" url_new_window=\"on\" use_icon=\"on\" font_icon=\"%%101%%\" icon_color=\"#b5b5b5\" use_circle=\"off\" circle_color=\"#0d76ec\" use_circle_border=\"off\" circle_border_color=\"#0d76ec\" icon_placement=\"left\" animation=\"top\" background_layout=\"light\" text_orientation=\"left\" use_icon_font_size=\"off\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"]<br \/> [\/et_pb_blurb][et_pb_divider admin_label=\"Modulo Separatore\" color=\"#b5b5b5\" show_divider=\"on\" divider_style=\"solid\" divider_position=\"top\" hide_on_mobile=\"on\" height=\"10\"]<br \/> [\/et_pb_divider][et_pb_text admin_label=\"Menu laterale - SUPER DATAMIX - ITA\" global_module=\"714\" saved_tabs=\"all\" background_layout=\"light\" text_orientation=\"left\" text_font_size=\"16\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"]<\/p><p><strong>SUPER DATAMIX<\/strong><\/p><ul><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/\">Introduzione<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-installazione-dellapp\/\">Installazione<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-attivazione-della-modalita-myscale\/\">Attivazione<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-segnalazioni-di-stato\/\">Segnalazioni di stato<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-stato-della-connessione\/\">Stato della connessione<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-funzione-dei-tasti\/\">Funzione dei tasti<\/a><\/li><li>Utilizzo del sistema<ul><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-utilizzo-della-tastiera\/\">Tastiera<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale\/\">Peso totale<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale-selezione-della-ricetta\/\">Selezione della ricetta<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale-azzeramento-del-peso-totale\/\">Azzeramento del peso totale<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale-carico-avvio-del-carico-della-ricetta\/\">Peso totale carico<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale-scarico-avvio-dello-scarico-della-ricetta\/\">Peso totale scarico<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-parziale-azzeramento-del-peso-parziale\/\">Peso parziale<\/a><\/li><\/ul><\/li><\/ul><p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\"3_4\" specialty_columns=\"3\"][et_pb_row_inner admin_label=\"Riga\"][et_pb_column_inner type=\"4_4\" saved_specialty_column_type=\"3_4\"][et_pb_cta admin_label=\"Titolo sezione\" title=\"Anagrafica clienti\" url_new_window=\"off\" use_background_color=\"off\" background_color=\"#0d76ec\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" custom_button=\"off\" button_letter_spacing=\"0\" button_use_icon=\"default\" button_icon_placement=\"right\" button_on_hover=\"on\" button_letter_spacing_hover=\"0\" header_font_size=\"40\"] [\/et_pb_cta][et_pb_text admin_label=\"Testo\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"]<\/p><p><img class=\"alignnone size-full wp-image-732\" src=\"http:\/\/demo.n-3.it\/ptm\/wp-content\/uploads\/2016\/11\/ptm_0013_anagrafica-clienti.jpg\" alt=\"ptm_0013_anagrafica-clienti\" width=\"467\" height=\"339\" \/><\/p><p>In questo men\u00f9 \u00e8 possibile creare un\u2019anagrafica clienti da utilizzare nella creazione dei carri.<\/p><p>Nella tabella di sinistra [8] viene visualizzato l'elenco dei clienti inseriti, mentre nella parte di destra viene visualizzato il dettaglio del cliente selezionato.<\/p><p>Ogni cliente \u00e8 costituito dai seguenti dati:<\/p><p>- <strong>Ragione sociale<\/strong> [10]: ragione sociale del cliente (massimo 40 caratteri alfanumerici)<\/p><p>- <strong>Indirizzo <\/strong>[11]: indirizzo del cliente<\/p><p>- <strong>Comune <\/strong>[12]: comune del cliente<\/p><p>- <strong>Provincia<\/strong> [13]: provincia<\/p><p>- <strong>CAP<\/strong> [14]: codice di avviamento postale<\/p><p>- <strong>Nazione<\/strong> [15]: nazione di riferimento<\/p><p>- <strong>Telefono<\/strong> [16]: numero di telefono<\/p><p>- <strong>Fax <\/strong>[17]: numero di fax<\/p><p>- <strong>E-mail<\/strong> [18]: indirizzo e-mail<\/p><p>- <strong>Partita IVA<\/strong> [19]: partita IVA<\/p><p>- <strong>Note <\/strong>[20]: annotazioni riguardanti il cliente<\/p><p>\u00a0<\/p><p>Se si desidera visualizzare un rapporto stampabile dei clienti inseriti premere \"Report\" [6].<\/p><p>[\/et_pb_text][et_pb_divider admin_label=\"Modulo Separatore\" color=\"#bababa\" show_divider=\"on\" height=\"10\" divider_style=\"solid\" divider_position=\"top\" hide_on_mobile=\"on\"]<br \/> [\/et_pb_divider][et_pb_cta admin_label=\"Link al form\" global_module=\"142\" saved_tabs=\"all\" title=\"Non trovi quello che cerchi?\" button_url=\"#\" url_new_window=\"off\" button_text=\"Contattaci\" use_background_color=\"off\" background_color=\"#0d76ec\" background_layout=\"light\" text_orientation=\"center\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" custom_button=\"off\" button_letter_spacing=\"0\" button_use_icon=\"default\" button_icon_placement=\"right\" button_on_hover=\"on\" button_letter_spacing_hover=\"0\"]<br \/> [\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/837"}],"collection":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/comments?post=837"}],"version-history":[{"count":0,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/837\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/785"}],"wp:attachment":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/media?parent=837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}