{"id":655,"date":"2016-11-07T15:29:44","date_gmt":"2016-11-07T14:29:44","guid":{"rendered":"http:\/\/demo.n-3.it\/ptm\/en\/?page_id=655"},"modified":"2016-11-07T16:43:56","modified_gmt":"2016-11-07T15:43:56","slug":"state-signallings","status":"publish","type":"page","link":"http:\/\/service.ptmsrl.com\/en\/app-myscale\/state-signallings\/","title":{"rendered":"State Signallings"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8221;section&#8221; fullwidth=&#8221;on&#8221;][et_pb_fullwidth_header admin_label=&#8221;Header &#8211; App MyScale&#8221; title=&#8221;APP MYSCALE&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; header_fullscreen=&#8221;off&#8221; header_scroll_down=&#8221;off&#8221; background_color=&#8221;#222349&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; content_orientation=&#8221;center&#8221; image_orientation=&#8221;center&#8221; title_font_color=&#8221;#ffffff&#8221; title_font=&#8221;Montserrat|on|||&#8221; title_font_size=&#8221;40px&#8221; custom_button_one=&#8221;off&#8221; button_one_letter_spacing=&#8221;0&#8243; button_one_use_icon=&#8221;default&#8221; button_one_icon_placement=&#8221;right&#8221; button_one_on_hover=&#8221;on&#8221; button_one_letter_spacing_hover=&#8221;0&#8243; custom_button_two=&#8221;off&#8221; button_two_letter_spacing=&#8221;0&#8243; button_two_use_icon=&#8221;default&#8221; button_two_icon_placement=&#8221;right&#8221; button_two_on_hover=&#8221;on&#8221; button_two_letter_spacing_hover=&#8221;0&#8243;] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=&#8221;Sezione&#8221; fullwidth=&#8221;off&#8221; specialty=&#8221;on&#8221; transparent_background=&#8221;off&#8221; background_color=&#8221;#ffffff&#8221; allow_player_pause=&#8221;off&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;0px|||&#8221; padding_mobile=&#8221;off&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221; make_equal=&#8221;off&#8221; use_custom_gutter=&#8221;off&#8221; parallax_1=&#8221;off&#8221; parallax_method_1=&#8221;off&#8221; parallax_2=&#8221;off&#8221; parallax_method_2=&#8221;off&#8221; custom_css_main_1=&#8221;border-right: solid 1px #bababa;&#8221;][et_pb_column type=&#8221;1_4&#8243;][et_pb_blurb admin_label=&#8221;Link al prodotto &#8211; APP MYSCALE &#8211; ITA&#8221; global_module=&#8221;548&#8243; saved_tabs=&#8221;all&#8221; title=&#8221;Scheda prodotto&#8221; url=&#8221;http:\/\/www.ptmsrl.com\/it\/s47\/product\/&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%101%%&#8221; icon_color=&#8221;#b5b5b5&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#0d76ec&#8221; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#0d76ec&#8221; icon_placement=&#8221;left&#8221; animation=&#8221;top&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_icon_font_size=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;] App MyScale [\/et_pb_blurb][et_pb_divider admin_label=&#8221;Modulo Separatore&#8221; color=&#8221;#b5b5b5&#8243; show_divider=&#8221;on&#8221; divider_style=&#8221;solid&#8221; divider_position=&#8221;top&#8221; hide_on_mobile=&#8221;on&#8221; height=&#8221;10&#8243;] [\/et_pb_divider][et_pb_text admin_label=&#8221;Menu laterale &#8211; APP MYSCALE &#8211; ITA&#8221; global_module=&#8221;554&#8243; saved_tabs=&#8221;all&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; text_font_size=&#8221;16&#8243; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p><strong>APP MYSCALE<\/strong><\/p>\n<ul>\n<li>Installazione<\/li>\n<li>Attivazione modalit\u00e0 AppScale<\/li>\n<li>Segnalazioni di stato<\/li>\n<li>Stato della connessione<\/li>\n<li>Funzione dei tasti<\/li>\n<li>Utilizzo del sistema<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; specialty_columns=&#8221;3&#8243;][et_pb_row_inner admin_label=&#8221;Riga&#8221;][et_pb_column_inner type=&#8221;4_4&#8243; saved_specialty_column_type=&#8221;3_4&#8243;][et_pb_cta admin_label=&#8221;Titolo sezione&#8221; title=&#8221;State Signallings&#8221; url_new_window=&#8221;off&#8221; use_background_color=&#8221;off&#8221; background_color=&#8221;#0d76ec&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; custom_button=&#8221;off&#8221; button_letter_spacing=&#8221;0&#8243; button_use_icon=&#8221;default&#8221; button_icon_placement=&#8221;right&#8221; button_on_hover=&#8221;on&#8221; button_letter_spacing_hover=&#8221;0&#8243; header_font_size=&#8221;40&#8243;] [\/et_pb_cta][et_pb_text admin_label=&#8221;Testo&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p>In the TOTAL WEIGHT screen page it is possible to see the connection status of the MySclae app and possible error reportings.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-675\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/total-weight.jpg\" alt=\"total-weight\" width=\"230\" height=\"173\" \/><\/p>\n<p>The connection status is indicated by an icon composed in the following way:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-569\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/appmyscale_icona.jpg\" alt=\"appmyscale_icona\" width=\"60\" height=\"52\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_divider admin_label=&#8221;Modulo Separatore&#8221; color=&#8221;#bababa&#8221; show_divider=&#8221;on&#8221; height=&#8221;10&#8243; divider_style=&#8221;solid&#8221; divider_position=&#8221;top&#8221; hide_on_mobile=&#8221;on&#8221;] [\/et_pb_divider][et_pb_cta admin_label=&#8221;Link al form&#8221; global_module=&#8221;142&#8243; saved_tabs=&#8221;all&#8221; title=&#8221;Non trovi quello che cerchi?&#8221; button_url=&#8221;#&#8221; url_new_window=&#8221;off&#8221; button_text=&#8221;Contattaci&#8221; use_background_color=&#8221;off&#8221; background_color=&#8221;#0d76ec&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;center&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; custom_button=&#8221;off&#8221; button_letter_spacing=&#8221;0&#8243; button_use_icon=&#8221;default&#8221; button_icon_placement=&#8221;right&#8221; button_on_hover=&#8221;on&#8221; button_letter_spacing_hover=&#8221;0&#8243;] [\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>App MyScale APP MYSCALE Installazione Attivazione modalit\u00e0 AppScale Segnalazioni di stato Stato della connessione Funzione dei tasti Utilizzo del sistema In the TOTAL WEIGHT screen page it is possible to see the connection status of the MySclae app and possible error reportings. The connection status is indicated by an icon composed in the following way: [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":637,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>[et_pb_section admin_label=\"section\" global_module=\"542\" fullwidth=\"on\"][et_pb_fullwidth_header global_parent=\"542\" admin_label=\"Header - App MyScale\" title=\"APP MYSCALE\" background_layout=\"light\" text_orientation=\"left\" header_fullscreen=\"off\" header_scroll_down=\"off\" background_color=\"#222349\" parallax=\"off\" parallax_method=\"off\" content_orientation=\"center\" image_orientation=\"center\" title_font_color=\"#ffffff\" title_font=\"Montserrat|on|||\" title_font_size=\"40px\" custom_button_one=\"off\" button_one_letter_spacing=\"0\" button_one_use_icon=\"default\" button_one_icon_placement=\"right\" button_one_on_hover=\"on\" button_one_letter_spacing_hover=\"0\" custom_button_two=\"off\" button_two_letter_spacing=\"0\" button_two_use_icon=\"default\" button_two_icon_placement=\"right\" button_two_on_hover=\"on\" button_two_letter_spacing_hover=\"0\"] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=\"Sezione\" fullwidth=\"off\" specialty=\"on\" transparent_background=\"off\" background_color=\"#ffffff\" allow_player_pause=\"off\" inner_shadow=\"off\" parallax=\"off\" parallax_method=\"off\" custom_padding=\"0px|||\" padding_mobile=\"off\" make_fullwidth=\"off\" use_custom_width=\"off\" width_unit=\"on\" make_equal=\"off\" use_custom_gutter=\"off\" parallax_1=\"off\" parallax_method_1=\"off\" parallax_2=\"off\" parallax_method_2=\"off\" custom_css_main_1=\"border-right: solid 1px #bababa;\"][et_pb_column type=\"1_4\"][et_pb_blurb admin_label=\"Link al prodotto - APP MYSCALE - ITA\" global_module=\"548\" saved_tabs=\"all\" title=\"Scheda prodotto\" url=\"http:\/\/www.ptmsrl.com\/it\/s47\/product\/\" url_new_window=\"on\" use_icon=\"on\" font_icon=\"%%101%%\" icon_color=\"#b5b5b5\" use_circle=\"off\" circle_color=\"#0d76ec\" use_circle_border=\"off\" circle_border_color=\"#0d76ec\" icon_placement=\"left\" animation=\"top\" background_layout=\"light\" text_orientation=\"left\" use_icon_font_size=\"off\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"] App MyScale [\/et_pb_blurb][et_pb_divider admin_label=\"Modulo Separatore\" color=\"#b5b5b5\" show_divider=\"on\" divider_style=\"solid\" divider_position=\"top\" hide_on_mobile=\"on\" height=\"10\"] [\/et_pb_divider][et_pb_text admin_label=\"Menu laterale - APP MYSCALE - ITA\" global_module=\"554\" saved_tabs=\"all\" background_layout=\"light\" text_orientation=\"left\" text_font_size=\"16\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"]<\/p><p><strong>APP MYSCALE<\/strong><\/p><ul><li>Installazione<\/li><li>Attivazione modalit\u00e0 AppScale<\/li><li>Segnalazioni di stato<\/li><li>Stato della connessione<\/li><li>Funzione dei tasti<\/li><li>Utilizzo del sistema<\/li><\/ul><p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\"3_4\" specialty_columns=\"3\"][et_pb_row_inner admin_label=\"Riga\"][et_pb_column_inner type=\"4_4\" saved_specialty_column_type=\"3_4\"][et_pb_cta admin_label=\"Titolo sezione\" title=\"Segnalazioni di stato\" url_new_window=\"off\" use_background_color=\"off\" background_color=\"#0d76ec\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" custom_button=\"off\" button_letter_spacing=\"0\" button_use_icon=\"default\" button_icon_placement=\"right\" button_on_hover=\"on\" button_letter_spacing_hover=\"0\" header_font_size=\"40\"] [\/et_pb_cta][et_pb_text admin_label=\"Testo\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"]<\/p><p>Una volta attivata la funzionalit\u00e0, nella schermata di PESO TOTALE \u00e8 possibile visualizzare lo stato della connessione all\u2019app MyScale e le eventuali segnalazioni di errore.<\/p><p><img class=\"alignnone size-full wp-image-567\" src=\"http:\/\/demo.n-3.it\/ptm\/wp-content\/uploads\/2016\/11\/segnalazioni-di-statp-appmyscale.jpg\" alt=\"segnalazioni-di-statp-appmyscale\" width=\"230\" height=\"173\" \/><\/p><p>Lo stato della connessione \u00e8 indicato da un\u2019icona cos\u00ec composta:<\/p><p><img class=\"alignnone size-full wp-image-569\" src=\"http:\/\/demo.n-3.it\/ptm\/wp-content\/uploads\/2016\/11\/appmyscale_icona.jpg\" alt=\"appmyscale_icona\" width=\"60\" height=\"52\" \/><\/p><p>\u00a0<\/p><p>[\/et_pb_text][et_pb_divider admin_label=\"Modulo Separatore\" color=\"#bababa\" show_divider=\"on\" height=\"10\" divider_style=\"solid\" divider_position=\"top\" hide_on_mobile=\"on\"] [\/et_pb_divider][et_pb_cta admin_label=\"Link al form\" global_module=\"142\" saved_tabs=\"all\" title=\"Non trovi quello che cerchi?\" button_url=\"#\" url_new_window=\"off\" button_text=\"Contattaci\" use_background_color=\"off\" background_color=\"#0d76ec\" background_layout=\"light\" text_orientation=\"center\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" custom_button=\"off\" button_letter_spacing=\"0\" button_use_icon=\"default\" button_icon_placement=\"right\" button_on_hover=\"on\" button_letter_spacing_hover=\"0\"] [\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/655"}],"collection":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/comments?post=655"}],"version-history":[{"count":0,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/655\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/637"}],"wp:attachment":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/media?parent=655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}