{"id":1344,"date":"2016-11-11T12:08:20","date_gmt":"2016-11-11T11:08:20","guid":{"rendered":"http:\/\/demo.n-3.it\/ptm\/en\/?page_id=1344"},"modified":"2016-11-11T12:08:20","modified_gmt":"2016-11-11T11:08:20","slug":"components","status":"publish","type":"page","link":"http:\/\/service.ptmsrl.com\/en\/datamix-card-3\/components\/","title":{"rendered":"Components"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8221;Header &#8211; Datamix Card &#8211; ITA&#8221; fullwidth=&#8221;on&#8221; specialty=&#8221;off&#8221; transparent_background=&#8221;off&#8221; background_color=&#8221;#ffffff&#8221; allow_player_pause=&#8221;off&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; padding_mobile=&#8221;off&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221; make_equal=&#8221;off&#8221; use_custom_gutter=&#8221;off&#8221;][et_pb_fullwidth_header admin_label=&#8221;Intestazione a Larghezza Piena&#8221; title=&#8221;DATAMIX CARD 3&#8243; background_layout=&#8221;dark&#8221; text_orientation=&#8221;left&#8221; header_fullscreen=&#8221;off&#8221; header_scroll_down=&#8221;off&#8221; background_color=&#8221;#222349&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; content_orientation=&#8221;center&#8221; image_orientation=&#8221;center&#8221; title_font_color=&#8221;#ffffff&#8221; title_font=&#8221;Montserrat|on|||&#8221; title_font_size=&#8221;40px&#8221; custom_button_one=&#8221;off&#8221; button_one_letter_spacing=&#8221;0&#8243; button_one_use_icon=&#8221;default&#8221; button_one_icon_placement=&#8221;right&#8221; button_one_on_hover=&#8221;on&#8221; button_one_letter_spacing_hover=&#8221;0&#8243; custom_button_two=&#8221;off&#8221; button_two_letter_spacing=&#8221;0&#8243; button_two_use_icon=&#8221;default&#8221; button_two_icon_placement=&#8221;right&#8221; button_two_on_hover=&#8221;on&#8221; button_two_letter_spacing_hover=&#8221;0&#8243;] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=&#8221;Sezione&#8221; fullwidth=&#8221;off&#8221; specialty=&#8221;on&#8221; transparent_background=&#8221;off&#8221; background_color=&#8221;#ffffff&#8221; allow_player_pause=&#8221;off&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;0px|||&#8221; padding_mobile=&#8221;off&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221; make_equal=&#8221;off&#8221; use_custom_gutter=&#8221;off&#8221; parallax_1=&#8221;off&#8221; parallax_method_1=&#8221;off&#8221; parallax_2=&#8221;off&#8221; parallax_method_2=&#8221;off&#8221; custom_css_main_1=&#8221;border-right: solid 1px #bababa;&#8221;][et_pb_column type=&#8221;1_4&#8243;][et_pb_blurb admin_label=&#8221;Scheda prodotto&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;off&#8221; icon_color=&#8221;#0d76ec&#8221; use_circle=&#8221;off&#8221; circle_color=&#8221;#0d76ec&#8221; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#0d76ec&#8221; icon_placement=&#8221;top&#8221; animation=&#8221;top&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_icon_font_size=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; saved_tabs=&#8221;all&#8221; global_module=&#8221;1213&#8243;] [\/et_pb_blurb][et_pb_divider admin_label=&#8221;Modulo Separatore&#8221; color=&#8221;#b5b5b5&#8243; show_divider=&#8221;on&#8221; divider_style=&#8221;solid&#8221; divider_position=&#8221;top&#8221; hide_on_mobile=&#8221;on&#8221; height=&#8221;10&#8243;] [\/et_pb_divider][et_pb_text admin_label=&#8221;Menu laterale &#8211; Datamix Card &#8211; ITA&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; saved_tabs=&#8221;all&#8221; global_module=&#8221;1215&#8243;]<\/p>\n<p><strong>DATAMIX CARD<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/\">Introduzione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-installazione-dellapp\/\">Installazione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-attivazione-della-modalita-myscale\/\">Attivazione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-segnalazioni-di-stato\/\">Segnalazioni di stato<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-stato-della-connessione\/\">Stato della connessione<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-funzione-dei-tasti\/\">Funzione dei tasti<\/a><\/li>\n<li>Utilizzo del sistema\n<ul>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-utilizzo-della-tastiera\/\">Tastiera<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale\/\">Peso totale<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-selezione-della-ricetta\/\">Selezione della ricetta<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-azzeramento-del-peso-totale\/\">Azzeramento del peso totale<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-carico-avvio-del-carico-della-ricetta\/\">Peso totale carico<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-totale-scarico-avvio-dello-scarico-della-ricetta\/\">Peso totale scarico<\/a><\/li>\n<li><a href=\"http:\/\/service.ptmsrl.com\/guida-app-myscale\/guida-app-myscale-peso-parziale-azzeramento-del-peso-parziale\/\">Peso parziale<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; specialty_columns=&#8221;3&#8243;][et_pb_row_inner admin_label=&#8221;Riga&#8221;][et_pb_column_inner type=&#8221;4_4&#8243; saved_specialty_column_type=&#8221;3_4&#8243;][et_pb_cta admin_label=&#8221;Titolo sezione&#8221; title=&#8221;Components&#8221; url_new_window=&#8221;off&#8221; use_background_color=&#8221;off&#8221; background_color=&#8221;#0d76ec&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; custom_button=&#8221;off&#8221; button_letter_spacing=&#8221;0&#8243; button_use_icon=&#8221;default&#8221; button_icon_placement=&#8221;right&#8221; button_on_hover=&#8221;on&#8221; button_letter_spacing_hover=&#8221;0&#8243; header_font_size=&#8221;40&#8243;] [\/et_pb_cta][et_pb_text admin_label=&#8221;Testo&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1336 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm_0008_datamix-card-eng.jpg\" width=\"289\" height=\"225\" \/><\/p>\n<p>The components in this table-sheet (Drw.1) are the main basic ingredients of the various recipes. Each one is associated to the cost per kg. The maximum number of components is 40.<\/p>\n<p><strong><em>Drw.1<\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1335 size-full\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm_0007_datamix-card-eng.jpg\" width=\"289\" height=\"225\" \/><\/p>\n<p>You can print the complete list of the components, using the key &#8220;Print&#8221;\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1256\" src=\"http:\/\/service.ptmsrl.com\/wp-content\/uploads\/2016\/11\/ptm_0006_icons.jpg\" alt=\"ptm_0006_icons\" width=\"80\" height=\"32\" \/><\/p>\n<p>It is also possible to modify the components or their cost using this table-sheet.<\/p>\n<p>[\/et_pb_text][et_pb_divider admin_label=&#8221;Modulo Separatore&#8221; color=&#8221;#bababa&#8221; show_divider=&#8221;on&#8221; height=&#8221;10&#8243; divider_style=&#8221;solid&#8221; divider_position=&#8221;top&#8221; hide_on_mobile=&#8221;on&#8221;] [\/et_pb_divider][et_pb_cta admin_label=&#8221;Link al form&#8221; global_module=&#8221;142&#8243; saved_tabs=&#8221;all&#8221; title=&#8221;Non trovi quello che cerchi?&#8221; button_url=&#8221;#&#8221; url_new_window=&#8221;off&#8221; button_text=&#8221;Contattaci&#8221; use_background_color=&#8221;off&#8221; background_color=&#8221;#0d76ec&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;center&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; custom_button=&#8221;off&#8221; button_letter_spacing=&#8221;0&#8243; button_use_icon=&#8221;default&#8221; button_icon_placement=&#8221;right&#8221; button_on_hover=&#8221;on&#8221; button_letter_spacing_hover=&#8221;0&#8243;] [\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DATAMIX CARD Introduzione Installazione Attivazione Segnalazioni di stato Stato della connessione Funzione dei tasti Utilizzo del sistema Tastiera Peso totale Selezione della ricetta Azzeramento del peso totale Peso totale carico Peso totale scarico Peso parziale The components in this table-sheet (Drw.1) are the main basic ingredients of the various recipes. Each one is associated to [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":1322,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>[et_pb_section admin_label=\"Header - Datamix Card - ITA\" global_module=\"1218\" fullwidth=\"on\" specialty=\"off\" transparent_background=\"off\" background_color=\"#ffffff\" allow_player_pause=\"off\" inner_shadow=\"off\" parallax=\"off\" parallax_method=\"off\" padding_mobile=\"off\" make_fullwidth=\"off\" use_custom_width=\"off\" width_unit=\"on\" make_equal=\"off\" use_custom_gutter=\"off\"][et_pb_fullwidth_header global_parent=\"1218\" admin_label=\"Intestazione a Larghezza Piena\" title=\"DATAMIX CARD 3\" background_layout=\"dark\" text_orientation=\"left\" header_fullscreen=\"off\" header_scroll_down=\"off\" background_color=\"#222349\" parallax=\"off\" parallax_method=\"off\" content_orientation=\"center\" image_orientation=\"center\" title_font_color=\"#ffffff\" title_font=\"Montserrat|on|||\" title_font_size=\"40px\" custom_button_one=\"off\" button_one_letter_spacing=\"0\" button_one_use_icon=\"default\" button_one_icon_placement=\"right\" button_one_on_hover=\"on\" button_one_letter_spacing_hover=\"0\" custom_button_two=\"off\" button_two_letter_spacing=\"0\" button_two_use_icon=\"default\" button_two_icon_placement=\"right\" button_two_on_hover=\"on\" button_two_letter_spacing_hover=\"0\"] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=\"Sezione\" fullwidth=\"off\" specialty=\"on\" transparent_background=\"off\" background_color=\"#ffffff\" allow_player_pause=\"off\" inner_shadow=\"off\" parallax=\"off\" parallax_method=\"off\" custom_padding=\"0px|||\" padding_mobile=\"off\" make_fullwidth=\"off\" use_custom_width=\"off\" width_unit=\"on\" make_equal=\"off\" use_custom_gutter=\"off\" parallax_1=\"off\" parallax_method_1=\"off\" parallax_2=\"off\" parallax_method_2=\"off\" custom_css_main_1=\"border-right: solid 1px #bababa;\"][et_pb_column type=\"1_4\"][et_pb_blurb admin_label=\"Scheda prodotto\" url_new_window=\"on\" use_icon=\"off\" icon_color=\"#0d76ec\" use_circle=\"off\" circle_color=\"#0d76ec\" use_circle_border=\"off\" circle_border_color=\"#0d76ec\" icon_placement=\"top\" animation=\"top\" background_layout=\"light\" text_orientation=\"left\" use_icon_font_size=\"off\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" saved_tabs=\"all\" global_module=\"1213\"] [\/et_pb_blurb][et_pb_divider admin_label=\"Modulo Separatore\" color=\"#b5b5b5\" show_divider=\"on\" divider_style=\"solid\" divider_position=\"top\" hide_on_mobile=\"on\" height=\"10\"] [\/et_pb_divider][et_pb_text admin_label=\"Menu laterale - Datamix Card - ITA\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" saved_tabs=\"all\" global_module=\"1215\"]<\/p><p><strong>DATAMIX CARD<\/strong><\/p><ul><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/\">Introduzione<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-installazione-dellapp\/\">Installazione<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-attivazione-della-modalita-myscale\/\">Attivazione<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-segnalazioni-di-stato\/\">Segnalazioni di stato<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-stato-della-connessione\/\">Stato della connessione<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-funzione-dei-tasti\/\">Funzione dei tasti<\/a><\/li><li>Utilizzo del sistema<ul><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-utilizzo-della-tastiera\/\">Tastiera<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale\/\">Peso totale<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale-selezione-della-ricetta\/\">Selezione della ricetta<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale-azzeramento-del-peso-totale\/\">Azzeramento del peso totale<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale-carico-avvio-del-carico-della-ricetta\/\">Peso totale carico<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-totale-scarico-avvio-dello-scarico-della-ricetta\/\">Peso totale scarico<\/a><\/li><li><a href=\"http:\/\/demo.n-3.it\/ptm\/guida-app-myscale\/guida-app-myscale-peso-parziale-azzeramento-del-peso-parziale\/\">Peso parziale<\/a><\/li><\/ul><\/li><\/ul><p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\"3_4\" specialty_columns=\"3\"][et_pb_row_inner admin_label=\"Riga\"][et_pb_column_inner type=\"4_4\" saved_specialty_column_type=\"3_4\"][et_pb_cta admin_label=\"Titolo sezione\" title=\"Componenti\" url_new_window=\"off\" use_background_color=\"off\" background_color=\"#0d76ec\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" custom_button=\"off\" button_letter_spacing=\"0\" button_use_icon=\"default\" button_icon_placement=\"right\" button_on_hover=\"on\" button_letter_spacing_hover=\"0\" header_font_size=\"40\"] [\/et_pb_cta][et_pb_text admin_label=\"Testo\" background_layout=\"light\" text_orientation=\"left\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\"]<\/p><p><img class=\"alignnone size-full wp-image-1236\" src=\"http:\/\/demo.n-3.it\/ptm\/wp-content\/uploads\/2016\/11\/ptm_0008_datamix-card.jpg\" alt=\"ptm_0008_datamix-card\" width=\"289\" height=\"225\" \/><\/p><p>I componenti contenuti in questa tabella (Fig.1) costituiscono gli ingredienti di base delle varie ricette. Ad ognuno di essi \u00e8 associato il costo al chilogrammo. Il nr. massimo di componenti \u00e8 40.<\/p><p><strong><em>Fig.1<\/em><\/strong><\/p><p><img class=\"alignnone wp-image-1235 size-full\" src=\"http:\/\/demo.n-3.it\/ptm\/wp-content\/uploads\/2016\/11\/ptm_0007_datamix-card.jpg\" width=\"289\" height=\"225\" \/><\/p><p>\u00c8 possibile stampare la lista completa dei componenti tramite il pulsante \"Stampa\"\u00a0<img class=\"alignnone size-full wp-image-1256\" src=\"http:\/\/demo.n-3.it\/ptm\/wp-content\/uploads\/2016\/11\/ptm_0006_icons.jpg\" alt=\"ptm_0006_icons\" width=\"80\" height=\"32\" \/><\/p><p>Per la modifica dei componenti o del loro costo \u00e8 sufficiente modificare i dati nella tabella.<\/p><p>\u00a0<\/p><p>[\/et_pb_text][et_pb_divider admin_label=\"Modulo Separatore\" color=\"#bababa\" show_divider=\"on\" height=\"10\" divider_style=\"solid\" divider_position=\"top\" hide_on_mobile=\"on\"] [\/et_pb_divider][et_pb_cta admin_label=\"Link al form\" global_module=\"142\" saved_tabs=\"all\" title=\"Non trovi quello che cerchi?\" button_url=\"#\" url_new_window=\"off\" button_text=\"Contattaci\" use_background_color=\"off\" background_color=\"#0d76ec\" background_layout=\"light\" text_orientation=\"center\" use_border_color=\"off\" border_color=\"#ffffff\" border_style=\"solid\" custom_button=\"off\" button_letter_spacing=\"0\" button_use_icon=\"default\" button_icon_placement=\"right\" button_on_hover=\"on\" button_letter_spacing_hover=\"0\"] [\/et_pb_cta][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/1344"}],"collection":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/comments?post=1344"}],"version-history":[{"count":0,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/1344\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/pages\/1322"}],"wp:attachment":[{"href":"http:\/\/service.ptmsrl.com\/en\/wp-json\/wp\/v2\/media?parent=1344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}